{"id":3928,"date":"2021-07-01T12:00:30","date_gmt":"2021-07-01T17:00:30","guid":{"rendered":"https:\/\/lepsa.com\/?p=3928"},"modified":"2023-06-16T11:53:28","modified_gmt":"2023-06-16T16:53:28","slug":"fabricacion-e-instalacion-de-soporte-interior-de-mist-filter-para-la-planta-de-acido-sulfurico-de-la-refineria-de-talara-pmrt","status":"publish","type":"post","link":"https:\/\/lepsa.com\/en\/noticias\/fabricacion-e-instalacion-de-soporte-interior-de-mist-filter-para-la-planta-de-acido-sulfurico-de-la-refineria-de-talara-pmrt\/","title":{"rendered":"Manufacturing and installation of Mist Filter interior support for Talara Refinery (PMRT)"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"3928\" class=\"elementor elementor-3928\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0b1a9ad elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"0b1a9ad\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-aae8874\" data-id=\"aae8874\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-be36be3 elementor-widget elementor-widget-text-editor\" data-id=\"be36be3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>\n\t\t<!-- MasterSlider -->\n\t\t<div id=\"P_MS6a57fd546ba34\" class=\"master-slider-parent msl ms-parent-id-3\" style=\"\">\n\n\t\t\t\n\t\t\t<!-- MasterSlider Main -->\n\t\t\t<div id=\"MS6a57fd546ba34\" class=\"master-slider ms-skin-light-3\" >\n\t\t\t\t \t\t\t\t \n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"6\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/lepsa.com\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/lepsa.com\/wp-content\/uploads\/2021\/01\/01-1.jpg\" \/>\n\n\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"6\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/lepsa.com\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/lepsa.com\/wp-content\/uploads\/2021\/01\/total_header_3.jpg\" \/>\n\n\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"6\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/lepsa.com\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/lepsa.com\/wp-content\/uploads\/2021\/01\/03-1.jpg\" \/>\n\n\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"6\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/lepsa.com\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/lepsa.com\/wp-content\/uploads\/2021\/01\/04-1-scaled.jpg\" \/>\n\n\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"6\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/lepsa.com\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/lepsa.com\/wp-content\/uploads\/2021\/01\/05-1.jpg\" \/>\n\n\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"6\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/lepsa.com\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/lepsa.com\/wp-content\/uploads\/2021\/01\/06-1.jpg\" \/>\n\n\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t<!-- END MasterSlider Main -->\n\n\t\t\t \n\t\t<\/div>\n\t\t<!-- END MasterSlider -->\n\n\t\t<script>\n\t\t(function ( $ ) {\n\t\t\t\"use strict\";\n\n\t\t\t$(function () {\n\t\t\t\tvar masterslider_ba34 = new MasterSlider();\n\n\t\t\t\t\/\/ slider controls\n\n\t\t\t\t\/\/ slider setup\n\t\t\t\tmasterslider_ba34.setup(\"MS6a57fd546ba34\", {\n\t\t\t\t\t\twidth           : 800,\n\t\t\t\t\t\theight          : 300,\n\t\t\t\t\t\tminHeight       : 0,\n\t\t\t\t\t\tspace           : 0,\n\t\t\t\t\t\tstart           : 1,\n\t\t\t\t\t\tgrabCursor      : false,\n\t\t\t\t\t\tswipe           : false,\n\t\t\t\t\t\tmouse           : false,\n\t\t\t\t\t\tlayout          : \"fullwidth\",\n\t\t\t\t\t\twheel           : false,\n\t\t\t\t\t\tautoplay        : true,\n\t\t\t\t\t\tinstantStartLayers:false,\n\t\t\t\t\t\tloop            : true,\n\t\t\t\t\t\tshuffle         : true,\n\t\t\t\t\t\tpreload         : 0,\n\t\t\t\t\t\theightLimit     : true,\n\t\t\t\t\t\tautoHeight      : false,\n\t\t\t\t\t\tsmoothHeight    : true,\n\t\t\t\t\t\tendPause        : false,\n\t\t\t\t\t\toverPause       : false,\n\t\t\t\t\t\tfillMode        : \"fill\",\n\t\t\t\t\t\tcenterControls  : true,\n\t\t\t\t\t\tstartOnAppear   : false,\n\t\t\t\t\t\tlayersMode      : \"center\",\n\t\t\t\t\t\thideLayers      : false,\n\t\t\t\t\t\tfullscreenMargin: 0,\n\t\t\t\t\t\tspeed           : 20,\n\t\t\t\t\t\tdir             : \"h\",\n\t\t\t\t\t\tparallaxMode    : 'swipe',\n\t\t\t\t\t\tview            : \"basic\"\n\t\t\t\t});\n\n\t\t\t\t\n\t\t\t\twindow.masterslider_instances = window.masterslider_instances || [];\n\t\t\t\twindow.masterslider_instances.push( masterslider_ba34 );\n\t\t\t });\n\n\t\t})(jQuery);\n\t\t<\/script>\n\n<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9cce139 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9cce139\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a14f941\" data-id=\"a14f941\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6ceb090 elementor-widget elementor-widget-heading\" data-id=\"6ceb090\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Manufacturing and installation of Mist Filter interior support for Talara Refinery (PMRT)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-808d16f elementor-widget elementor-widget-text-editor\" data-id=\"808d16f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p class=\"MsoNormal\" style=\"text-align: justify;\">In July 2021, LEPSA received the contract from COBRA for the supply of the inner support plate for the Mist Filter equipment, \u00d8 5400 mm x 278 mm, made of high-end Epoxy Vinylester Novolac resin, intermediate layers in FRP (Fiberglass Reinforced Plastic) and external layer with 5 mm thick polypropylene (PP) liner (outer surface), structurally designed with a maximum deflection of 20 mm.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aedebb0 elementor-widget elementor-widget-image\" data-id=\"aedebb0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"447\" src=\"https:\/\/lepsa.com\/wp-content\/uploads\/2021\/07\/CBR-027_3_px1200-1024x572.jpg\" class=\"attachment-large size-large wp-image-3995\" alt=\"\" srcset=\"https:\/\/lepsa.com\/wp-content\/uploads\/2021\/07\/CBR-027_3_px1200-1024x572.jpg 1024w, https:\/\/lepsa.com\/wp-content\/uploads\/2021\/07\/CBR-027_3_px1200-300x168.jpg 300w, https:\/\/lepsa.com\/wp-content\/uploads\/2021\/07\/CBR-027_3_px1200-768x429.jpg 768w, https:\/\/lepsa.com\/wp-content\/uploads\/2021\/07\/CBR-027_3_px1200-18x10.jpg 18w, https:\/\/lepsa.com\/wp-content\/uploads\/2021\/07\/CBR-027_3_px1200-830x463.jpg 830w, https:\/\/lepsa.com\/wp-content\/uploads\/2021\/07\/CBR-027_3_px1200-230x128.jpg 230w, https:\/\/lepsa.com\/wp-content\/uploads\/2021\/07\/CBR-027_3_px1200-350x195.jpg 350w, https:\/\/lepsa.com\/wp-content\/uploads\/2021\/07\/CBR-027_3_px1200-480x268.jpg 480w, https:\/\/lepsa.com\/wp-content\/uploads\/2021\/07\/CBR-027_3_px1200.jpg 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d75b6cc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d75b6cc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-c2db499\" data-id=\"c2db499\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7d7ea65 elementor-widget elementor-widget-text-editor\" data-id=\"7d7ea65\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>The support is a special design capable of supporting more than 160 tons of dynamic load supported only at its ends. This challenge was met by LEPSA by applying all the recommendations of international standards.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-e9af40d elementor-widget elementor-widget-image\" data-id=\"e9af40d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"448\" data-src=\"https:\/\/lepsa.com\/wp-content\/uploads\/2021\/06\/CBR-027_1_px1200-1024x573.jpg\" class=\"attachment-large size-large wp-image-3932 lazyload\" alt=\"\" data-srcset=\"https:\/\/lepsa.com\/wp-content\/uploads\/2021\/06\/CBR-027_1_px1200-1024x573.jpg 1024w, https:\/\/lepsa.com\/wp-content\/uploads\/2021\/06\/CBR-027_1_px1200-300x168.jpg 300w, https:\/\/lepsa.com\/wp-content\/uploads\/2021\/06\/CBR-027_1_px1200-768x430.jpg 768w, https:\/\/lepsa.com\/wp-content\/uploads\/2021\/06\/CBR-027_1_px1200-18x10.jpg 18w, https:\/\/lepsa.com\/wp-content\/uploads\/2021\/06\/CBR-027_1_px1200-830x465.jpg 830w, https:\/\/lepsa.com\/wp-content\/uploads\/2021\/06\/CBR-027_1_px1200-230x129.jpg 230w, https:\/\/lepsa.com\/wp-content\/uploads\/2021\/06\/CBR-027_1_px1200-350x196.jpg 350w, https:\/\/lepsa.com\/wp-content\/uploads\/2021\/06\/CBR-027_1_px1200-480x269.jpg 480w, https:\/\/lepsa.com\/wp-content\/uploads\/2021\/06\/CBR-027_1_px1200.jpg 1200w\" data-sizes=\"(max-width: 800px) 100vw, 800px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 800px; --smush-placeholder-aspect-ratio: 800\/448;\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f384e22 elementor-widget elementor-widget-image\" data-id=\"f384e22\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"448\" data-src=\"https:\/\/lepsa.com\/wp-content\/uploads\/2021\/06\/CBR-027_2_px1200-1024x573.jpg\" class=\"attachment-large size-large wp-image-3933 lazyload\" alt=\"\" data-srcset=\"https:\/\/lepsa.com\/wp-content\/uploads\/2021\/06\/CBR-027_2_px1200-1024x573.jpg 1024w, https:\/\/lepsa.com\/wp-content\/uploads\/2021\/06\/CBR-027_2_px1200-300x168.jpg 300w, https:\/\/lepsa.com\/wp-content\/uploads\/2021\/06\/CBR-027_2_px1200-768x430.jpg 768w, https:\/\/lepsa.com\/wp-content\/uploads\/2021\/06\/CBR-027_2_px1200-18x10.jpg 18w, https:\/\/lepsa.com\/wp-content\/uploads\/2021\/06\/CBR-027_2_px1200-830x465.jpg 830w, https:\/\/lepsa.com\/wp-content\/uploads\/2021\/06\/CBR-027_2_px1200-230x129.jpg 230w, https:\/\/lepsa.com\/wp-content\/uploads\/2021\/06\/CBR-027_2_px1200-350x196.jpg 350w, https:\/\/lepsa.com\/wp-content\/uploads\/2021\/06\/CBR-027_2_px1200-480x269.jpg 480w, https:\/\/lepsa.com\/wp-content\/uploads\/2021\/06\/CBR-027_2_px1200.jpg 1200w\" data-sizes=\"(max-width: 800px) 100vw, 800px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 800px; --smush-placeholder-aspect-ratio: 800\/448;\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-43f6a83 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"43f6a83\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-deefb07\" data-id=\"deefb07\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a96fd86 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"a96fd86\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/lepsa.com\/en\/temporal\/noticias\/\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Back to News\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-circle-left\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/lepsa.com\/en\/temporal\/noticias\/\" >\n\t\t\t\t\t\t\tBack to News\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>July 2021<\/p>","protected":false},"author":1,"featured_media":3932,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-3928","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fabricaci\u00f3n e instalaci\u00f3n de soporte interior de Mist Filter para la Refiner\u00eda de Talara (PMRT) | LEPSA<\/title>\n<meta name=\"description\" content=\"Conoce m\u00e1s sobre Fabricaci\u00f3n e instalaci\u00f3n de soporte interior de Mist Filter para la Refiner\u00eda de Talara (PMRT) en LEPSA .\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lepsa.com\/en\/noticias\/fabricacion-e-instalacion-de-soporte-interior-de-mist-filter-para-la-planta-de-acido-sulfurico-de-la-refineria-de-talara-pmrt\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fabricaci\u00f3n e instalaci\u00f3n de soporte interior de Mist Filter para la Refiner\u00eda de Talara (PMRT) | LEPSA\" \/>\n<meta property=\"og:description\" content=\"Conoce m\u00e1s sobre Fabricaci\u00f3n e instalaci\u00f3n de soporte interior de Mist Filter para la Refiner\u00eda de Talara (PMRT) en LEPSA .\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lepsa.com\/en\/noticias\/fabricacion-e-instalacion-de-soporte-interior-de-mist-filter-para-la-planta-de-acido-sulfurico-de-la-refineria-de-talara-pmrt\/\" \/>\n<meta property=\"og:site_name\" content=\"LEPSA\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-01T17:00:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-16T16:53:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lepsa.com\/wp-content\/uploads\/2021\/06\/CBR-027_1_px1200.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"672\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ko78jdhy\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/lepsa.com\/noticias\/fabricacion-e-instalacion-de-soporte-interior-de-mist-filter-para-la-planta-de-acido-sulfurico-de-la-refineria-de-talara-pmrt\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/lepsa.com\/noticias\/fabricacion-e-instalacion-de-soporte-interior-de-mist-filter-para-la-planta-de-acido-sulfurico-de-la-refineria-de-talara-pmrt\/\"},\"author\":{\"name\":\"Ko78jdhy\",\"@id\":\"https:\/\/lepsa.com\/#\/schema\/person\/a53ac2500ca9d6db733d82f57935851a\"},\"headline\":\"Fabricaci\u00f3n e instalaci\u00f3n de soporte interior de Mist Filter para la Refiner\u00eda de Talara (PMRT)\",\"datePublished\":\"2021-07-01T17:00:30+00:00\",\"dateModified\":\"2023-06-16T16:53:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/lepsa.com\/noticias\/fabricacion-e-instalacion-de-soporte-interior-de-mist-filter-para-la-planta-de-acido-sulfurico-de-la-refineria-de-talara-pmrt\/\"},\"wordCount\":156,\"publisher\":{\"@id\":\"https:\/\/lepsa.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/lepsa.com\/noticias\/fabricacion-e-instalacion-de-soporte-interior-de-mist-filter-para-la-planta-de-acido-sulfurico-de-la-refineria-de-talara-pmrt\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/lepsa.com\/wp-content\/uploads\/2021\/06\/CBR-027_1_px1200.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/lepsa.com\/noticias\/fabricacion-e-instalacion-de-soporte-interior-de-mist-filter-para-la-planta-de-acido-sulfurico-de-la-refineria-de-talara-pmrt\/\",\"url\":\"https:\/\/lepsa.com\/noticias\/fabricacion-e-instalacion-de-soporte-interior-de-mist-filter-para-la-planta-de-acido-sulfurico-de-la-refineria-de-talara-pmrt\/\",\"name\":\"Fabricaci\u00f3n e instalaci\u00f3n de soporte interior de Mist Filter para la Refiner\u00eda de Talara (PMRT) | LEPSA\",\"isPartOf\":{\"@id\":\"https:\/\/lepsa.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/lepsa.com\/noticias\/fabricacion-e-instalacion-de-soporte-interior-de-mist-filter-para-la-planta-de-acido-sulfurico-de-la-refineria-de-talara-pmrt\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/lepsa.com\/noticias\/fabricacion-e-instalacion-de-soporte-interior-de-mist-filter-para-la-planta-de-acido-sulfurico-de-la-refineria-de-talara-pmrt\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/lepsa.com\/wp-content\/uploads\/2021\/06\/CBR-027_1_px1200.jpg\",\"datePublished\":\"2021-07-01T17:00:30+00:00\",\"dateModified\":\"2023-06-16T16:53:28+00:00\",\"description\":\"Conoce m\u00e1s sobre Fabricaci\u00f3n e instalaci\u00f3n de soporte interior de Mist Filter para la Refiner\u00eda de Talara (PMRT) en LEPSA .\",\"breadcrumb\":{\"@id\":\"https:\/\/lepsa.com\/noticias\/fabricacion-e-instalacion-de-soporte-interior-de-mist-filter-para-la-planta-de-acido-sulfurico-de-la-refineria-de-talara-pmrt\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/lepsa.com\/noticias\/fabricacion-e-instalacion-de-soporte-interior-de-mist-filter-para-la-planta-de-acido-sulfurico-de-la-refineria-de-talara-pmrt\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/lepsa.com\/noticias\/fabricacion-e-instalacion-de-soporte-interior-de-mist-filter-para-la-planta-de-acido-sulfurico-de-la-refineria-de-talara-pmrt\/#primaryimage\",\"url\":\"https:\/\/lepsa.com\/wp-content\/uploads\/2021\/06\/CBR-027_1_px1200.jpg\",\"contentUrl\":\"https:\/\/lepsa.com\/wp-content\/uploads\/2021\/06\/CBR-027_1_px1200.jpg\",\"width\":1200,\"height\":672},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/lepsa.com\/noticias\/fabricacion-e-instalacion-de-soporte-interior-de-mist-filter-para-la-planta-de-acido-sulfurico-de-la-refineria-de-talara-pmrt\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/lepsa.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fabricaci\u00f3n e instalaci\u00f3n de soporte interior de Mist Filter para la Refiner\u00eda de Talara (PMRT)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/lepsa.com\/#website\",\"url\":\"https:\/\/lepsa.com\/\",\"name\":\"LEPSA\",\"description\":\"Soluciones integrales para la industria y miner\u00eda\",\"publisher\":{\"@id\":\"https:\/\/lepsa.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/lepsa.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/lepsa.com\/#organization\",\"name\":\"LEPSA\",\"url\":\"https:\/\/lepsa.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/lepsa.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/lepsa.com\/wp-content\/uploads\/2021\/01\/lepsa.jpg\",\"contentUrl\":\"https:\/\/lepsa.com\/wp-content\/uploads\/2021\/01\/lepsa.jpg\",\"width\":725,\"height\":297,\"caption\":\"LEPSA\"},\"image\":{\"@id\":\"https:\/\/lepsa.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/lepsa-s-a-c\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/lepsa.com\/#\/schema\/person\/a53ac2500ca9d6db733d82f57935851a\",\"name\":\"Ko78jdhy\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/lepsa.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/51e1c3b3167e278078aa9b8afcd93991671058efe93290eace26c7d30c241063?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/51e1c3b3167e278078aa9b8afcd93991671058efe93290eace26c7d30c241063?s=96&r=g\",\"caption\":\"Ko78jdhy\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fabricaci\u00f3n e instalaci\u00f3n de soporte interior de Mist Filter para la Refiner\u00eda de Talara (PMRT) | LEPSA","description":"Conoce m\u00e1s sobre Fabricaci\u00f3n e instalaci\u00f3n de soporte interior de Mist Filter para la Refiner\u00eda de Talara (PMRT) en LEPSA .","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lepsa.com\/en\/noticias\/fabricacion-e-instalacion-de-soporte-interior-de-mist-filter-para-la-planta-de-acido-sulfurico-de-la-refineria-de-talara-pmrt\/","og_locale":"en_US","og_type":"article","og_title":"Fabricaci\u00f3n e instalaci\u00f3n de soporte interior de Mist Filter para la Refiner\u00eda de Talara (PMRT) | LEPSA","og_description":"Conoce m\u00e1s sobre Fabricaci\u00f3n e instalaci\u00f3n de soporte interior de Mist Filter para la Refiner\u00eda de Talara (PMRT) en LEPSA .","og_url":"https:\/\/lepsa.com\/en\/noticias\/fabricacion-e-instalacion-de-soporte-interior-de-mist-filter-para-la-planta-de-acido-sulfurico-de-la-refineria-de-talara-pmrt\/","og_site_name":"LEPSA","article_published_time":"2021-07-01T17:00:30+00:00","article_modified_time":"2023-06-16T16:53:28+00:00","og_image":[{"width":1200,"height":672,"url":"https:\/\/lepsa.com\/wp-content\/uploads\/2021\/06\/CBR-027_1_px1200.jpg","type":"image\/jpeg"}],"author":"Ko78jdhy","twitter_card":"summary_large_image","twitter_misc":{"Written by":false,"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lepsa.com\/noticias\/fabricacion-e-instalacion-de-soporte-interior-de-mist-filter-para-la-planta-de-acido-sulfurico-de-la-refineria-de-talara-pmrt\/#article","isPartOf":{"@id":"https:\/\/lepsa.com\/noticias\/fabricacion-e-instalacion-de-soporte-interior-de-mist-filter-para-la-planta-de-acido-sulfurico-de-la-refineria-de-talara-pmrt\/"},"author":{"name":"Ko78jdhy","@id":"https:\/\/lepsa.com\/#\/schema\/person\/a53ac2500ca9d6db733d82f57935851a"},"headline":"Fabricaci\u00f3n e instalaci\u00f3n de soporte interior de Mist Filter para la Refiner\u00eda de Talara (PMRT)","datePublished":"2021-07-01T17:00:30+00:00","dateModified":"2023-06-16T16:53:28+00:00","mainEntityOfPage":{"@id":"https:\/\/lepsa.com\/noticias\/fabricacion-e-instalacion-de-soporte-interior-de-mist-filter-para-la-planta-de-acido-sulfurico-de-la-refineria-de-talara-pmrt\/"},"wordCount":156,"publisher":{"@id":"https:\/\/lepsa.com\/#organization"},"image":{"@id":"https:\/\/lepsa.com\/noticias\/fabricacion-e-instalacion-de-soporte-interior-de-mist-filter-para-la-planta-de-acido-sulfurico-de-la-refineria-de-talara-pmrt\/#primaryimage"},"thumbnailUrl":"https:\/\/lepsa.com\/wp-content\/uploads\/2021\/06\/CBR-027_1_px1200.jpg","articleSection":["Noticias"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/lepsa.com\/noticias\/fabricacion-e-instalacion-de-soporte-interior-de-mist-filter-para-la-planta-de-acido-sulfurico-de-la-refineria-de-talara-pmrt\/","url":"https:\/\/lepsa.com\/noticias\/fabricacion-e-instalacion-de-soporte-interior-de-mist-filter-para-la-planta-de-acido-sulfurico-de-la-refineria-de-talara-pmrt\/","name":"Fabricaci\u00f3n e instalaci\u00f3n de soporte interior de Mist Filter para la Refiner\u00eda de Talara (PMRT) | LEPSA","isPartOf":{"@id":"https:\/\/lepsa.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lepsa.com\/noticias\/fabricacion-e-instalacion-de-soporte-interior-de-mist-filter-para-la-planta-de-acido-sulfurico-de-la-refineria-de-talara-pmrt\/#primaryimage"},"image":{"@id":"https:\/\/lepsa.com\/noticias\/fabricacion-e-instalacion-de-soporte-interior-de-mist-filter-para-la-planta-de-acido-sulfurico-de-la-refineria-de-talara-pmrt\/#primaryimage"},"thumbnailUrl":"https:\/\/lepsa.com\/wp-content\/uploads\/2021\/06\/CBR-027_1_px1200.jpg","datePublished":"2021-07-01T17:00:30+00:00","dateModified":"2023-06-16T16:53:28+00:00","description":"Conoce m\u00e1s sobre Fabricaci\u00f3n e instalaci\u00f3n de soporte interior de Mist Filter para la Refiner\u00eda de Talara (PMRT) en LEPSA .","breadcrumb":{"@id":"https:\/\/lepsa.com\/noticias\/fabricacion-e-instalacion-de-soporte-interior-de-mist-filter-para-la-planta-de-acido-sulfurico-de-la-refineria-de-talara-pmrt\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lepsa.com\/noticias\/fabricacion-e-instalacion-de-soporte-interior-de-mist-filter-para-la-planta-de-acido-sulfurico-de-la-refineria-de-talara-pmrt\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lepsa.com\/noticias\/fabricacion-e-instalacion-de-soporte-interior-de-mist-filter-para-la-planta-de-acido-sulfurico-de-la-refineria-de-talara-pmrt\/#primaryimage","url":"https:\/\/lepsa.com\/wp-content\/uploads\/2021\/06\/CBR-027_1_px1200.jpg","contentUrl":"https:\/\/lepsa.com\/wp-content\/uploads\/2021\/06\/CBR-027_1_px1200.jpg","width":1200,"height":672},{"@type":"BreadcrumbList","@id":"https:\/\/lepsa.com\/noticias\/fabricacion-e-instalacion-de-soporte-interior-de-mist-filter-para-la-planta-de-acido-sulfurico-de-la-refineria-de-talara-pmrt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lepsa.com\/"},{"@type":"ListItem","position":2,"name":"Fabricaci\u00f3n e instalaci\u00f3n de soporte interior de Mist Filter para la Refiner\u00eda de Talara (PMRT)"}]},{"@type":"WebSite","@id":"https:\/\/lepsa.com\/#website","url":"https:\/\/lepsa.com\/","name":"LEPSA","description":"Soluciones integrales para la industria y miner\u00eda","publisher":{"@id":"https:\/\/lepsa.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lepsa.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/lepsa.com\/#organization","name":"LEPSA","url":"https:\/\/lepsa.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lepsa.com\/#\/schema\/logo\/image\/","url":"https:\/\/lepsa.com\/wp-content\/uploads\/2021\/01\/lepsa.jpg","contentUrl":"https:\/\/lepsa.com\/wp-content\/uploads\/2021\/01\/lepsa.jpg","width":725,"height":297,"caption":"LEPSA"},"image":{"@id":"https:\/\/lepsa.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/lepsa-s-a-c"]},{"@type":"Person","@id":"https:\/\/lepsa.com\/#\/schema\/person\/a53ac2500ca9d6db733d82f57935851a","name":"Ko78jdhy","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lepsa.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/51e1c3b3167e278078aa9b8afcd93991671058efe93290eace26c7d30c241063?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/51e1c3b3167e278078aa9b8afcd93991671058efe93290eace26c7d30c241063?s=96&r=g","caption":"Ko78jdhy"}}]}},"_links":{"self":[{"href":"https:\/\/lepsa.com\/en\/wp-json\/wp\/v2\/posts\/3928","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lepsa.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lepsa.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lepsa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lepsa.com\/en\/wp-json\/wp\/v2\/comments?post=3928"}],"version-history":[{"count":32,"href":"https:\/\/lepsa.com\/en\/wp-json\/wp\/v2\/posts\/3928\/revisions"}],"predecessor-version":[{"id":4841,"href":"https:\/\/lepsa.com\/en\/wp-json\/wp\/v2\/posts\/3928\/revisions\/4841"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lepsa.com\/en\/wp-json\/wp\/v2\/media\/3932"}],"wp:attachment":[{"href":"https:\/\/lepsa.com\/en\/wp-json\/wp\/v2\/media?parent=3928"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lepsa.com\/en\/wp-json\/wp\/v2\/categories?post=3928"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lepsa.com\/en\/wp-json\/wp\/v2\/tags?post=3928"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}