{"id":1644,"date":"2019-05-01T12:00:43","date_gmt":"2019-05-01T17:00:43","guid":{"rendered":"https:\/\/lepsa.com\/temporal\/?p=1644"},"modified":"2023-06-16T11:58:06","modified_gmt":"2023-06-16T16:58:06","slug":"decantadores-settlers-modulares","status":"publish","type":"post","link":"https:\/\/lepsa.com\/en\/proyectos\/decantadores-settlers-modulares\/","title":{"rendered":"Modular settlers"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"1644\" class=\"elementor elementor-1644\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0b1a9ad elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"0b1a9ad\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-aae8874\" data-id=\"aae8874\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-be36be3 elementor-widget elementor-widget-text-editor\" data-id=\"be36be3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>\n\t\t<!-- MasterSlider -->\n\t\t<div id=\"P_MS6a57ea338de5d\" class=\"master-slider-parent msl ms-parent-id-3\" style=\"\">\n\n\t\t\t\n\t\t\t<!-- MasterSlider Main -->\n\t\t\t<div id=\"MS6a57ea338de5d\" class=\"master-slider ms-skin-light-3\" >\n\t\t\t\t \t\t\t\t \n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"6\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/lepsa.com\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/lepsa.com\/wp-content\/uploads\/2021\/01\/01-1.jpg\" \/>\n\n\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"6\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/lepsa.com\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/lepsa.com\/wp-content\/uploads\/2021\/01\/total_header_3.jpg\" \/>\n\n\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"6\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/lepsa.com\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/lepsa.com\/wp-content\/uploads\/2021\/01\/03-1.jpg\" \/>\n\n\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"6\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/lepsa.com\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/lepsa.com\/wp-content\/uploads\/2021\/01\/04-1-scaled.jpg\" \/>\n\n\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"6\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/lepsa.com\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/lepsa.com\/wp-content\/uploads\/2021\/01\/05-1.jpg\" \/>\n\n\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div  class=\"ms-slide\" data-delay=\"6\" data-fill-mode=\"fill\"  >\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/lepsa.com\/wp-content\/plugins\/master-slider\/public\/assets\/css\/blank.gif\" alt=\"\" title=\"\" data-src=\"https:\/\/lepsa.com\/wp-content\/uploads\/2021\/01\/06-1.jpg\" \/>\n\n\n\t<div class=\"ms-thumb\" ><div class=\"ms-tab-context\"><div class=\"&quot;ms-tab-context&quot;\"><\/div><\/div>\n<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t\t<!-- END MasterSlider Main -->\n\n\t\t\t \n\t\t<\/div>\n\t\t<!-- END MasterSlider -->\n\n\t\t<script>\n\t\t(function ( $ ) {\n\t\t\t\"use strict\";\n\n\t\t\t$(function () {\n\t\t\t\tvar masterslider_de5d = new MasterSlider();\n\n\t\t\t\t\/\/ slider controls\n\n\t\t\t\t\/\/ slider setup\n\t\t\t\tmasterslider_de5d.setup(\"MS6a57ea338de5d\", {\n\t\t\t\t\t\twidth           : 800,\n\t\t\t\t\t\theight          : 300,\n\t\t\t\t\t\tminHeight       : 0,\n\t\t\t\t\t\tspace           : 0,\n\t\t\t\t\t\tstart           : 1,\n\t\t\t\t\t\tgrabCursor      : false,\n\t\t\t\t\t\tswipe           : false,\n\t\t\t\t\t\tmouse           : false,\n\t\t\t\t\t\tlayout          : \"fullwidth\",\n\t\t\t\t\t\twheel           : false,\n\t\t\t\t\t\tautoplay        : true,\n\t\t\t\t\t\tinstantStartLayers:false,\n\t\t\t\t\t\tloop            : true,\n\t\t\t\t\t\tshuffle         : true,\n\t\t\t\t\t\tpreload         : 0,\n\t\t\t\t\t\theightLimit     : true,\n\t\t\t\t\t\tautoHeight      : false,\n\t\t\t\t\t\tsmoothHeight    : true,\n\t\t\t\t\t\tendPause        : false,\n\t\t\t\t\t\toverPause       : false,\n\t\t\t\t\t\tfillMode        : \"fill\",\n\t\t\t\t\t\tcenterControls  : true,\n\t\t\t\t\t\tstartOnAppear   : false,\n\t\t\t\t\t\tlayersMode      : \"center\",\n\t\t\t\t\t\thideLayers      : false,\n\t\t\t\t\t\tfullscreenMargin: 0,\n\t\t\t\t\t\tspeed           : 20,\n\t\t\t\t\t\tdir             : \"h\",\n\t\t\t\t\t\tparallaxMode    : 'swipe',\n\t\t\t\t\t\tview            : \"basic\"\n\t\t\t\t});\n\n\t\t\t\t\n\t\t\t\twindow.masterslider_instances = window.masterslider_instances || [];\n\t\t\t\twindow.masterslider_instances.push( masterslider_de5d );\n\t\t\t });\n\n\t\t})(jQuery);\n\t\t<\/script>\n\n<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9cce139 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"9cce139\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a14f941\" data-id=\"a14f941\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6ceb090 elementor-widget elementor-widget-heading\" data-id=\"6ceb090\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Projects<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b642011 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"b642011\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-7cf37cd\" data-id=\"7cf37cd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a09ef6c elementor-widget elementor-widget-heading\" data-id=\"a09ef6c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">FRP Modular settlers<\/h4>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d75b6cc elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"d75b6cc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c2db499\" data-id=\"c2db499\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7d7ea65 elementor-widget elementor-widget-text-editor\" data-id=\"7d7ea65\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h5><span style=\"color: #3366ff;\"><strong>Equipment for SX\/EW refining process<\/strong><\/span><\/h5><p><strong>Client: TENOVA<\/strong><\/p><p><span style=\"color: #3366ff;\">Salar de Cauchar\u00ed, Argentina<\/span><\/p><ul><li><strong>Modular settlers<\/strong><\/li><li><strong>(02) modules per equipment<\/strong><\/li><li><strong>63.8 ft x 29.6 ft x 5.11 ft (LxWxH)<\/strong><\/li><li><strong>SX solution \/ organic<\/strong><\/li><li><strong>May 2019<\/strong><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-90205d0\" data-id=\"90205d0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6f2fd64 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"6f2fd64\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-1' class='gallery galleryid-1644 gallery-columns-3 gallery-size-sydney-medium-thumb'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"6f2fd64\" data-elementor-lightbox-title=\"1\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTY1MiwidXJsIjoiaHR0cHM6XC9cL2xlcHNhLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDFcLzEtMTYuanBnIiwic2xpZGVzaG93IjoiNmYyZmQ2NCJ9\" href='https:\/\/lepsa.com\/wp-content\/uploads\/2021\/01\/1-16.jpg'><img fetchpriority=\"high\" decoding=\"async\" width=\"550\" height=\"400\" src=\"https:\/\/lepsa.com\/wp-content\/uploads\/2021\/01\/1-16-550x400.jpg\" class=\"attachment-sydney-medium-thumb size-sydney-medium-thumb\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"6f2fd64\" data-elementor-lightbox-title=\"2\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTY1MywidXJsIjoiaHR0cHM6XC9cL2xlcHNhLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDFcLzItMTQuanBnIiwic2xpZGVzaG93IjoiNmYyZmQ2NCJ9\" href='https:\/\/lepsa.com\/wp-content\/uploads\/2021\/01\/2-14.jpg'><img decoding=\"async\" width=\"550\" height=\"400\" data-src=\"https:\/\/lepsa.com\/wp-content\/uploads\/2021\/01\/2-14-550x400.jpg\" class=\"attachment-sydney-medium-thumb size-sydney-medium-thumb lazyload\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 550px; --smush-placeholder-aspect-ratio: 550\/400;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"6f2fd64\" data-elementor-lightbox-title=\"6_1280w\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTY1NSwidXJsIjoiaHR0cHM6XC9cL2xlcHNhLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDFcLzZfMTI4MHcuanBnIiwic2xpZGVzaG93IjoiNmYyZmQ2NCJ9\" href='https:\/\/lepsa.com\/wp-content\/uploads\/2021\/01\/6_1280w.jpg'><img decoding=\"async\" width=\"550\" height=\"400\" data-src=\"https:\/\/lepsa.com\/wp-content\/uploads\/2021\/01\/6_1280w-550x400.jpg\" class=\"attachment-sydney-medium-thumb size-sydney-medium-thumb lazyload\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 550px; --smush-placeholder-aspect-ratio: 550\/400;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"6f2fd64\" data-elementor-lightbox-title=\"3\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTY1NCwidXJsIjoiaHR0cHM6XC9cL2xlcHNhLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDFcLzMtMTcuanBnIiwic2xpZGVzaG93IjoiNmYyZmQ2NCJ9\" href='https:\/\/lepsa.com\/wp-content\/uploads\/2021\/01\/3-17.jpg'><img decoding=\"async\" width=\"550\" height=\"400\" data-src=\"https:\/\/lepsa.com\/wp-content\/uploads\/2021\/01\/3-17-550x400.jpg\" class=\"attachment-sydney-medium-thumb size-sydney-medium-thumb lazyload\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 550px; --smush-placeholder-aspect-ratio: 550\/400;\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"6f2fd64\" data-elementor-lightbox-title=\"7_1280w\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTY1NiwidXJsIjoiaHR0cHM6XC9cL2xlcHNhLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMVwvMDFcLzdfMTI4MHcuanBnIiwic2xpZGVzaG93IjoiNmYyZmQ2NCJ9\" href='https:\/\/lepsa.com\/wp-content\/uploads\/2021\/01\/7_1280w.jpg'><img decoding=\"async\" width=\"550\" height=\"400\" data-src=\"https:\/\/lepsa.com\/wp-content\/uploads\/2021\/01\/7_1280w-550x400.jpg\" class=\"attachment-sydney-medium-thumb size-sydney-medium-thumb lazyload\" alt=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 550px; --smush-placeholder-aspect-ratio: 550\/400;\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-43f6a83 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"43f6a83\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-deefb07\" data-id=\"deefb07\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a96fd86 elementor-position-left elementor-view-default elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"a96fd86\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/lepsa.com\/en\/temporal\/proyectos\/\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Back to Projects\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-circle-left\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/lepsa.com\/en\/temporal\/proyectos\/\" >\n\t\t\t\t\t\t\tBack to Projects\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>May 2019<\/p>","protected":false},"author":4,"featured_media":1646,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1644","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-proyectos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Decantadores (Settlers) Modulares | LEPSA<\/title>\n<meta name=\"description\" content=\"Conoce m\u00e1s sobre Decantadores (Settlers) Modulares en LEPSA .\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lepsa.com\/en\/proyectos\/decantadores-settlers-modulares\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Decantadores (Settlers) Modulares | LEPSA\" \/>\n<meta property=\"og:description\" content=\"Conoce m\u00e1s sobre Decantadores (Settlers) Modulares en LEPSA .\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lepsa.com\/en\/proyectos\/decantadores-settlers-modulares\/\" \/>\n<meta property=\"og:site_name\" content=\"LEPSA\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-01T17:00:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-16T16:58:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lepsa.com\/wp-content\/uploads\/2020\/08\/4-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Milton\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/lepsa.com\/proyectos\/decantadores-settlers-modulares\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/lepsa.com\/proyectos\/decantadores-settlers-modulares\/\"},\"author\":{\"name\":\"Milton\",\"@id\":\"https:\/\/lepsa.com\/#\/schema\/person\/bb29270c6758f70cb1b93eaa7bc89b5b\"},\"headline\":\"Decantadores (Settlers) Modulares\",\"datePublished\":\"2019-05-01T17:00:43+00:00\",\"dateModified\":\"2023-06-16T16:58:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/lepsa.com\/proyectos\/decantadores-settlers-modulares\/\"},\"wordCount\":47,\"publisher\":{\"@id\":\"https:\/\/lepsa.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/lepsa.com\/proyectos\/decantadores-settlers-modulares\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/lepsa.com\/wp-content\/uploads\/2020\/08\/4-1.jpg\",\"articleSection\":[\"Proyectos\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/lepsa.com\/proyectos\/decantadores-settlers-modulares\/\",\"url\":\"https:\/\/lepsa.com\/proyectos\/decantadores-settlers-modulares\/\",\"name\":\"Decantadores (Settlers) Modulares | LEPSA\",\"isPartOf\":{\"@id\":\"https:\/\/lepsa.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/lepsa.com\/proyectos\/decantadores-settlers-modulares\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/lepsa.com\/proyectos\/decantadores-settlers-modulares\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/lepsa.com\/wp-content\/uploads\/2020\/08\/4-1.jpg\",\"datePublished\":\"2019-05-01T17:00:43+00:00\",\"dateModified\":\"2023-06-16T16:58:06+00:00\",\"description\":\"Conoce m\u00e1s sobre Decantadores (Settlers) Modulares en LEPSA .\",\"breadcrumb\":{\"@id\":\"https:\/\/lepsa.com\/proyectos\/decantadores-settlers-modulares\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/lepsa.com\/proyectos\/decantadores-settlers-modulares\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/lepsa.com\/proyectos\/decantadores-settlers-modulares\/#primaryimage\",\"url\":\"https:\/\/lepsa.com\/wp-content\/uploads\/2020\/08\/4-1.jpg\",\"contentUrl\":\"https:\/\/lepsa.com\/wp-content\/uploads\/2020\/08\/4-1.jpg\",\"width\":1280,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/lepsa.com\/proyectos\/decantadores-settlers-modulares\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/lepsa.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Decantadores (Settlers) Modulares\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/lepsa.com\/#website\",\"url\":\"https:\/\/lepsa.com\/\",\"name\":\"LEPSA\",\"description\":\"Soluciones integrales para la industria y miner\u00eda\",\"publisher\":{\"@id\":\"https:\/\/lepsa.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/lepsa.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/lepsa.com\/#organization\",\"name\":\"LEPSA\",\"url\":\"https:\/\/lepsa.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/lepsa.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/lepsa.com\/wp-content\/uploads\/2021\/01\/lepsa.jpg\",\"contentUrl\":\"https:\/\/lepsa.com\/wp-content\/uploads\/2021\/01\/lepsa.jpg\",\"width\":725,\"height\":297,\"caption\":\"LEPSA\"},\"image\":{\"@id\":\"https:\/\/lepsa.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/lepsa-s-a-c\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/lepsa.com\/#\/schema\/person\/bb29270c6758f70cb1b93eaa7bc89b5b\",\"name\":\"Milton\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/lepsa.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5e3926dfca6de31ed0e8949d1bb745f4cb0d89a1a2f72458f2ae8190b6a535b5?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5e3926dfca6de31ed0e8949d1bb745f4cb0d89a1a2f72458f2ae8190b6a535b5?s=96&r=g\",\"caption\":\"Milton\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Decantadores (Settlers) Modulares | LEPSA","description":"Conoce m\u00e1s sobre Decantadores (Settlers) Modulares en LEPSA .","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lepsa.com\/en\/proyectos\/decantadores-settlers-modulares\/","og_locale":"en_US","og_type":"article","og_title":"Decantadores (Settlers) Modulares | LEPSA","og_description":"Conoce m\u00e1s sobre Decantadores (Settlers) Modulares en LEPSA .","og_url":"https:\/\/lepsa.com\/en\/proyectos\/decantadores-settlers-modulares\/","og_site_name":"LEPSA","article_published_time":"2019-05-01T17:00:43+00:00","article_modified_time":"2023-06-16T16:58:06+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/lepsa.com\/wp-content\/uploads\/2020\/08\/4-1.jpg","type":"image\/jpeg"}],"author":"Milton","twitter_card":"summary_large_image","twitter_misc":{"Written by":false,"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lepsa.com\/proyectos\/decantadores-settlers-modulares\/#article","isPartOf":{"@id":"https:\/\/lepsa.com\/proyectos\/decantadores-settlers-modulares\/"},"author":{"name":"Milton","@id":"https:\/\/lepsa.com\/#\/schema\/person\/bb29270c6758f70cb1b93eaa7bc89b5b"},"headline":"Decantadores (Settlers) Modulares","datePublished":"2019-05-01T17:00:43+00:00","dateModified":"2023-06-16T16:58:06+00:00","mainEntityOfPage":{"@id":"https:\/\/lepsa.com\/proyectos\/decantadores-settlers-modulares\/"},"wordCount":47,"publisher":{"@id":"https:\/\/lepsa.com\/#organization"},"image":{"@id":"https:\/\/lepsa.com\/proyectos\/decantadores-settlers-modulares\/#primaryimage"},"thumbnailUrl":"https:\/\/lepsa.com\/wp-content\/uploads\/2020\/08\/4-1.jpg","articleSection":["Proyectos"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/lepsa.com\/proyectos\/decantadores-settlers-modulares\/","url":"https:\/\/lepsa.com\/proyectos\/decantadores-settlers-modulares\/","name":"Decantadores (Settlers) Modulares | LEPSA","isPartOf":{"@id":"https:\/\/lepsa.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lepsa.com\/proyectos\/decantadores-settlers-modulares\/#primaryimage"},"image":{"@id":"https:\/\/lepsa.com\/proyectos\/decantadores-settlers-modulares\/#primaryimage"},"thumbnailUrl":"https:\/\/lepsa.com\/wp-content\/uploads\/2020\/08\/4-1.jpg","datePublished":"2019-05-01T17:00:43+00:00","dateModified":"2023-06-16T16:58:06+00:00","description":"Conoce m\u00e1s sobre Decantadores (Settlers) Modulares en LEPSA .","breadcrumb":{"@id":"https:\/\/lepsa.com\/proyectos\/decantadores-settlers-modulares\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lepsa.com\/proyectos\/decantadores-settlers-modulares\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lepsa.com\/proyectos\/decantadores-settlers-modulares\/#primaryimage","url":"https:\/\/lepsa.com\/wp-content\/uploads\/2020\/08\/4-1.jpg","contentUrl":"https:\/\/lepsa.com\/wp-content\/uploads\/2020\/08\/4-1.jpg","width":1280,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/lepsa.com\/proyectos\/decantadores-settlers-modulares\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lepsa.com\/"},{"@type":"ListItem","position":2,"name":"Decantadores (Settlers) Modulares"}]},{"@type":"WebSite","@id":"https:\/\/lepsa.com\/#website","url":"https:\/\/lepsa.com\/","name":"LEPSA","description":"Soluciones integrales para la industria y miner\u00eda","publisher":{"@id":"https:\/\/lepsa.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lepsa.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/lepsa.com\/#organization","name":"LEPSA","url":"https:\/\/lepsa.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lepsa.com\/#\/schema\/logo\/image\/","url":"https:\/\/lepsa.com\/wp-content\/uploads\/2021\/01\/lepsa.jpg","contentUrl":"https:\/\/lepsa.com\/wp-content\/uploads\/2021\/01\/lepsa.jpg","width":725,"height":297,"caption":"LEPSA"},"image":{"@id":"https:\/\/lepsa.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/lepsa-s-a-c"]},{"@type":"Person","@id":"https:\/\/lepsa.com\/#\/schema\/person\/bb29270c6758f70cb1b93eaa7bc89b5b","name":"Milton","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lepsa.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5e3926dfca6de31ed0e8949d1bb745f4cb0d89a1a2f72458f2ae8190b6a535b5?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5e3926dfca6de31ed0e8949d1bb745f4cb0d89a1a2f72458f2ae8190b6a535b5?s=96&r=g","caption":"Milton"}}]}},"_links":{"self":[{"href":"https:\/\/lepsa.com\/en\/wp-json\/wp\/v2\/posts\/1644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lepsa.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lepsa.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lepsa.com\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lepsa.com\/en\/wp-json\/wp\/v2\/comments?post=1644"}],"version-history":[{"count":37,"href":"https:\/\/lepsa.com\/en\/wp-json\/wp\/v2\/posts\/1644\/revisions"}],"predecessor-version":[{"id":4895,"href":"https:\/\/lepsa.com\/en\/wp-json\/wp\/v2\/posts\/1644\/revisions\/4895"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lepsa.com\/en\/wp-json\/wp\/v2\/media\/1646"}],"wp:attachment":[{"href":"https:\/\/lepsa.com\/en\/wp-json\/wp\/v2\/media?parent=1644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lepsa.com\/en\/wp-json\/wp\/v2\/categories?post=1644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lepsa.com\/en\/wp-json\/wp\/v2\/tags?post=1644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}